{"id":1558,"date":"2025-10-30T15:53:53","date_gmt":"2025-10-30T15:53:53","guid":{"rendered":"https:\/\/consilient1stg.wpenginepowered.com\/yanae-patient\/?page_id=1558"},"modified":"2025-11-27T23:12:10","modified_gmt":"2025-11-27T23:12:10","slug":"about-yanae","status":"publish","type":"page","link":"https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/","title":{"rendered":"About Yanae"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1558","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>About Yanae - Yanae Patient<\/title>\n<meta name=\"description\" content=\"about Yanae information for patients in Ireland.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About Yanae - Yanae Patient\" \/>\n<meta property=\"og:description\" content=\"about Yanae information for patients in Ireland.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/\" \/>\n<meta property=\"og:site_name\" content=\"Yanae Patient\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-27T23:12:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/\",\"url\":\"https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/\",\"name\":\"About Yanae - Yanae Patient\",\"isPartOf\":{\"@id\":\"https:\/\/www.consilienthealth.ie\/yanae-patient\/#website\"},\"datePublished\":\"2025-10-30T15:53:53+00:00\",\"dateModified\":\"2025-11-27T23:12:10+00:00\",\"description\":\"about Yanae information for patients in Ireland.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.consilienthealth.ie\/yanae-patient\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About Yanae\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.consilienthealth.ie\/yanae-patient\/#website\",\"url\":\"https:\/\/www.consilienthealth.ie\/yanae-patient\/\",\"name\":\"Yanae Patient\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.consilienthealth.ie\/yanae-patient\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About Yanae - Yanae Patient","description":"about Yanae information for patients in Ireland.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/","og_locale":"en_US","og_type":"article","og_title":"About Yanae - Yanae Patient","og_description":"about Yanae information for patients in Ireland.","og_url":"https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/","og_site_name":"Yanae Patient","article_modified_time":"2025-11-27T23:12:10+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/","url":"https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/","name":"About Yanae - Yanae Patient","isPartOf":{"@id":"https:\/\/www.consilienthealth.ie\/yanae-patient\/#website"},"datePublished":"2025-10-30T15:53:53+00:00","dateModified":"2025-11-27T23:12:10+00:00","description":"about Yanae information for patients in Ireland.","breadcrumb":{"@id":"https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consilienthealth.ie\/yanae-patient\/about-yanae\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.consilienthealth.ie\/yanae-patient\/"},{"@type":"ListItem","position":2,"name":"About Yanae"}]},{"@type":"WebSite","@id":"https:\/\/www.consilienthealth.ie\/yanae-patient\/#website","url":"https:\/\/www.consilienthealth.ie\/yanae-patient\/","name":"Yanae Patient","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consilienthealth.ie\/yanae-patient\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.consilienthealth.ie\/yanae-patient\/wp-json\/wp\/v2\/pages\/1558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consilienthealth.ie\/yanae-patient\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.consilienthealth.ie\/yanae-patient\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.consilienthealth.ie\/yanae-patient\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.consilienthealth.ie\/yanae-patient\/wp-json\/wp\/v2\/comments?post=1558"}],"version-history":[{"count":0,"href":"https:\/\/www.consilienthealth.ie\/yanae-patient\/wp-json\/wp\/v2\/pages\/1558\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.consilienthealth.ie\/yanae-patient\/wp-json\/wp\/v2\/media?parent=1558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}